{"id":70116,"date":"2025-09-29T11:40:45","date_gmt":"2025-09-29T09:40:45","guid":{"rendered":"https:\/\/tuftingeurope.com\/?p=70116"},"modified":"2025-09-30T15:25:12","modified_gmt":"2025-09-30T13:25:12","slug":"tinis-tufted-chair-full-of-play-and-process","status":"publish","type":"post","link":"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/tinis-tufted-chair-full-of-play-and-process\/","title":{"rendered":"La silla con tufting de Tini, llena de juego y proceso"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">En el coraz\u00f3n de Berl\u00edn, la artista <strong>Tini<\/strong> est\u00e1 dando una nueva vida a tesoros de segunda mano, un mech\u00f3n de tufting a la vez. Conocida por su curiosidad y su enfoque pr\u00e1ctico, siempre est\u00e1 explorando nuevos materiales y t\u00e9cnicas.  <\/h3>\n\n<p class=\"wp-block-paragraph\">Su \u00faltima creaci\u00f3n es en parte arte textil, en parte renovaci\u00f3n de muebles: una silla tapizada con tufting y reciclada que comenz\u00f3 con un hallazgo en la calle y termin\u00f3 con un mont\u00f3n de lana, color y lecciones aprendidas en el camino.<\/p>\n\n<p class=\"wp-block-paragraph\">El tufting lleg\u00f3 a la vida de Tini por primera vez en oto\u00f1o de 2022, a trav\u00e9s de un taller que r\u00e1pidamente despert\u00f3 un amor duradero por la artesan\u00eda. Sin embargo, no fue hasta dos a\u00f1os despu\u00e9s cuando consigui\u00f3 su propio equipo y realmente comenz\u00f3 a experimentar en su propio tiempo y espacio.  <\/p>\n\n<p class=\"wp-block-paragraph\">Lo que le atrajo fue la fisicidad del tufting, la satisfacci\u00f3n de hacer algo a mano, y c\u00f3mo simplemente hac\u00eda que todo lo dem\u00e1s se desvaneciera en el fondo. \u201cMe hace olvidar mis preocupaciones y problemas durante un peque\u00f1o lapso de tiempo\u201d <\/p>\n\n<h2 class=\"wp-block-heading\">\u267b\ufe0f Una silla tapizada con tufting y reciclada<\/h2>\n\n<p class=\"wp-block-paragraph\">La vio en la calle y decidi\u00f3 darle otra oportunidad. En lugar de pensar demasiado en el dise\u00f1o, se dej\u00f3 llevar, dibujando a mano alzada y trabajando con colores que simplemente le hac\u00edan sentir bien juntos. La idea no era aspirar a la perfecci\u00f3n, sino probar algo nuevo y disfrutar del proceso.  <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"1024\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-650x1024.jpeg\" alt=\"\" class=\"wp-image-70335\" style=\"width:425px;height:auto\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-650x1024.jpeg 650w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-190x300.jpeg 190w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-768x1210.jpeg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-975x1536.jpeg 975w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-1300x2048.jpeg 1300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-1320x2079.jpeg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-1000x1575.jpeg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-317x500.jpeg 317w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image7-scaled.jpeg 1625w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">A\u00fan as\u00ed, el proceso no estuvo exento de contratiempos. Intent\u00f3 usar yute como material de respaldo por primera vez, pero segu\u00eda rompi\u00e9ndose por razones que no pod\u00eda entender del todo. Despu\u00e9s de algunas frustrantes pruebas y errores, volvi\u00f3 al algod\u00f3n y comenz\u00f3 de nuevo. Otras lecciones vinieron del lado de la tapicer\u00eda: recortar gastos en material termin\u00f3 haciendo todo el proceso m\u00e1s dif\u00edcil.   <\/p>\n\n<p class=\"wp-block-paragraph\">\u201cDeber\u00eda haber hecho el respaldo en un marco nuevo en lugar de intentar meter todo en uno\u201d, admite. Al final, hab\u00eda <em>justo<\/em> suficiente superficie con tufting para cubrir el asiento y el respaldo, pero ya ha tomado nota de lo que har\u00eda diferente la pr\u00f3xima vez: ser m\u00e1s generosa con los materiales, e incluso darle otra oportunidad al yute, despu\u00e9s de averiguar qu\u00e9 sali\u00f3 mal. <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"69933\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-768x1024.jpeg\" alt=\"\" class=\"wp-image-69933\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-768x1024.jpeg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-225x300.jpeg 225w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-1152x1536.jpeg 1152w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-1536x2048.jpeg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-1320x1760.jpeg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-1000x1333.jpeg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-60x80.jpeg 60w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/IMG_0165-1e960d1a2d0d1c7b790e835cfb87a0fd-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"774\" height=\"1024\" data-id=\"70336\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-774x1024.jpeg\" alt=\"\" class=\"wp-image-70336\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-774x1024.jpeg 774w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-227x300.jpeg 227w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-768x1017.jpeg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-1160x1536.jpeg 1160w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-1547x2048.jpeg 1547w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-1320x1747.jpeg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-1000x1324.jpeg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-378x500.jpeg 378w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image2-scaled.jpeg 1934w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" data-id=\"70338\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image5-rotated.jpeg\" alt=\"\" class=\"wp-image-70338\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image5-rotated.jpeg 480w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image5-225x300.jpeg 225w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image5-375x500.jpeg 375w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 del hilo y la tela, hubo una sorprendente cantidad de trabajo de detalle involucrado en la restauraci\u00f3n de la silla. Limpiar la suciedad del interior de las patas, pulir el marco, reemplazar los tornillos: cada peque\u00f1a tarea se sum\u00f3 a una pieza que se siente personal y completa. <\/p>\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s hermoso de este proyecto no es solo el resultado final, sino lo que representa. Tini ha encontrado en el tufting no solo una artesan\u00eda, sino un escape l\u00fadico, y una forma de suavizar sus tendencias perfeccionistas. \u201cEstoy muy contenta de haber conocido el tufting hace unos a\u00f1os\u201d, dice. \u201cMe ha ayudado a dejarme llevar y a realizar mis ideas de una manera m\u00e1s alegre e intuitiva\u201d.   <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"706\" height=\"1024\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-706x1024.jpeg\" alt=\"\" class=\"wp-image-70337\" style=\"width:317px;height:auto\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-706x1024.jpeg 706w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-207x300.jpeg 207w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-768x1114.jpeg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-1059x1536.jpeg 1059w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-1412x2048.jpeg 1412w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-1320x1915.jpeg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-1000x1451.jpeg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-345x500.jpeg 345w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/image0-scaled.jpeg 1765w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/figure>\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Puede seguir el colorido y siempre cambiante viaje de Tini en Instagram en <a href=\"https:\/\/instagram.com\/tinituft\" target=\"_blank\" rel=\"noopener\">@tinituft<\/a>. Ya sean muebles viejos o lana fresca, tiene un don para convertir lo que se pasa por alto en algo realmente especial. <\/p>\n\n\n  \n    <div id=\"row-1364983011\" class=\"row large-columns-3 medium-columns-1 small-columns-1 row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/therugdealers-tufted-porsche-three-years-in-the-making\/\" class=\"plain\" aria-label=\"El Porsche con tufting de TheRugDealer, tres a\u00f1os en preparaci\u00f3n\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-1320x743.jpg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/11\/the-rug-dealer-porsche-tufted-tufting-rug-car.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/therugdealers-tufted-porsche-three-years-in-the-making\/\" class=\"plain\">El Porsche con tufting de TheRugDealer, tres a\u00f1os en preparaci\u00f3n<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/tinis-tufted-chair-full-of-play-and-process\/\" class=\"plain\" aria-label=\"La silla con tufting de Tini, llena de juego y proceso\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-1320x743.jpg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-3.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/tinis-tufted-chair-full-of-play-and-process\/\" class=\"plain\">La silla con tufting de Tini, llena de juego y proceso<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/oslo-rugs-tribute-to-footballs-greatest-rivalry\/\" class=\"plain\" aria-label=\"El tributo de Oslo Rugs a la mayor rivalidad del f\u00fatbol\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-1320x743.jpg 1320w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/09\/Rug-of-the-week-series-tuftingeurope-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/oslo-rugs-tribute-to-footballs-greatest-rivalry\/\" class=\"plain\">El tributo de Oslo Rugs a la mayor rivalidad del f\u00fatbol<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/cedric-vus-self-portrait-series-and-the-art-of-becoming\/\" class=\"plain\" aria-label=\"La Serie de Autorretratos de Cedric Vu y el Arte de Devenir\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/04\/Rug-of-the-week-series-tuftingeurope-3.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/cedric-vus-self-portrait-series-and-the-art-of-becoming\/\" class=\"plain\">La Serie de Autorretratos de Cedric Vu y el Arte de Devenir<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/hippolyte-goberts-ocean-inspired-tufting-art\/\" class=\"plain\" aria-label=\"El arte de tufting inspirado en el oc\u00e9ano de Hippolyte Gobert\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/03\/Rug-of-the-week-series-tuftingeurope-1.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/hippolyte-goberts-ocean-inspired-tufting-art\/\" class=\"plain\">El arte de tufting inspirado en el oc\u00e9ano de Hippolyte Gobert<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/kid-kardiacs-tribute-to-kobe-and-the-power-of-preserving-moments\/\" class=\"plain\" aria-label=\"El homenaje de Kid Kardiac a Kobe y el poder de preservar momentos\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-300x169.jpg 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-1024x576.jpg 1024w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-768x432.jpg 768w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-1536x864.jpg 1536w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-1000x563.jpg 1000w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7-80x45.jpg 80w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2025\/02\/Rug-of-the-week-series-tuftingeurope-7.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/tuftingeurope.com\/es\/alfombra-de-la-semana\/kid-kardiacs-tribute-to-kobe-and-the-power-of-preserving-moments\/\" class=\"plain\">El homenaje de Kid Kardiac a Kobe y el poder de preservar momentos<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el coraz\u00f3n de Berl\u00edn, la artista Tini est\u00e1 dando una nueva vida a tesoros de segunda mano, un mech\u00f3n de tufting a la vez. Conocida por su curiosidad y su enfoque pr\u00e1ctico, siempre est\u00e1 explorando nuevos materiales y t\u00e9cnicas. Su \u00faltima creaci\u00f3n es en parte arte textil, en parte renovaci\u00f3n de muebles: una silla<\/p>\n","protected":false},"author":1,"featured_media":70347,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"bwfblock_default_font":"","footnotes":""},"categories":[757],"tags":[],"class_list":["post-70116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfombra-de-la-semana"],"_links":{"self":[{"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/posts\/70116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/comments?post=70116"}],"version-history":[{"count":2,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/posts\/70116\/revisions"}],"predecessor-version":[{"id":70405,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/posts\/70116\/revisions\/70405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/media\/70347"}],"wp:attachment":[{"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/media?parent=70116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/categories?post=70116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuftingeurope.com\/es\/wp-json\/wp\/v2\/tags?post=70116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}