{"id":48966,"date":"2024-10-07T03:28:46","date_gmt":"2024-10-07T01:28:46","guid":{"rendered":"https:\/\/tuftingeurope.com\/product\/filato-per-tufting-in-lana-viola-melanzana-500-g\/"},"modified":"2026-07-12T22:30:04","modified_gmt":"2026-07-12T20:30:04","slug":"dark-purple-tufting-yarn-500g-wool","status":"publish","type":"product","link":"https:\/\/tuftingeurope.com\/it\/prodotto\/dark-purple-tufting-yarn-500g-wool\/","title":{"rendered":"Viola scuro 500 g di lana Filato per tufting"},"content":{"rendered":"<h2>Filato per Tufting Viola Scuro in Lana Neozelandese 100%<\/h2>\n<p>Viola Scuro \u00e8 un viola ricco e profondo dall&#8217;aspetto regale. Funziona come base elegante o come accento deciso e si abbina a crema, oro, rosa cipria e grigio. <\/p>\n<p>Come ogni tonalit\u00e0 della nostra gamma di 52 colori, Viola Scuro \u00e8 lana neozelandese 100% filata specificamente per il tufting, quindi riempie la tela primaria, mantiene un pelo pulito e conserva il suo colore per anni di utilizzo.<br \/>\n&nbsp;<\/p>\n<h2>Perch\u00e9 chi fa tufting sceglie la nostra lana della Nuova Zelanda<\/h2>\n<ul>\n<li><strong>100% lana della Nuova Zelanda:<\/strong> morbida, naturalmente elastica e ricca di colore.<\/li>\n<li><strong>Filata per il tufting a 837\/3 tex:<\/strong> il peso ideale per un ago da 4 mm, a filo singolo o doppio, senza intasamenti.<\/li>\n<li><strong>600 metri per ogni rocca da 500 g:<\/strong> pi\u00f9 lunghezza con cui lavorare su ogni rocca.<\/li>\n<li><strong>Filatura fitta, bassa perdita di fibre:<\/strong> rimane pulita nella pistola per un vello uniforme con il minimo di peluria.<\/li>\n<li><strong>Responsible Wool Standard:<\/strong> da allevamenti certificati RWS, per il benessere animale e la gestione responsabile del territorio.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Perch\u00e9 scegliere la lana per un tappeto che duri nel tempo<\/h2>\n<p>Un tappeto tufted richiede ore di lavoro e la lana \u00e8 la fibra che lo fa durare. La sua naturale arricciatura resiste al calpestio e ai mobili, mantenendo la forma del vello per anni. La lana \u00e8 naturalmente ignifuga, difficile da incendiare e autoestinguente, motivo per cui viene utilizzata nei tappeti per il settore contract e aeronautico. Respinge l&#8217;acqua e le macchie quotidiane, non accumula elettricit\u00e0 statica e risulta pi\u00f9 calda e morbida sotto i piedi.   <\/p>\n<p>Se curata, dura una vita intera. I tappeti antichi in lana sopravvivono per generazioni. Questa \u00e8 la fibra che chi fa tufting seriamente usa per i pezzi da vendere, esporre o conservare.<br \/>\n&nbsp;<br \/>\n\n<table id=\"tablepress-4\" class=\"tablepress tablepress-id-4\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Specifications<\/th><td class=\"column-2\"><\/td>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Material<\/td><td class=\"column-2\">100% New Zealand Sheeps Wool<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Animal Welfare<\/td><td class=\"column-2\">Responsible Wool Standard (RWS)<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Properties<\/td><td class=\"column-2\">Anti-pilling, Anti-static<br \/>\n<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Compostition<\/td><td class=\"column-2\">Core spun at 140 TPM<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Weight<\/td><td class=\"column-2\">500 grams approx<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Length<\/td><td class=\"column-2\">600 meters approx<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Tex<\/td><td class=\"column-2\">837\/3<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Needle Size<\/td><td class=\"column-2\">4mm<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Compatibility\t<\/td><td class=\"column-2\">Tufting, Knitting<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Coned?<\/td><td class=\"column-2\">Yes, cardboard cone<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-4 from cache -->\n&nbsp;<\/p>\n<h2>Certificato secondo il Responsible Wool Standard <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-49958 alignnone\" src=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo.png\" alt=\"Logo Responsible Wool Standard\" width=\"35\" height=\"35\" title=\"\" srcset=\"https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo.png 480w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo-300x300.png 300w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo-150x150.png 150w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo-360x360.png 360w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo-100x100.png 100w, https:\/\/tuftingeurope.com\/wp-content\/uploads\/2024\/10\/rws-logo-80x80.png 80w\" sizes=\"auto, (max-width: 35px) 100vw, 35px\" \/><\/h2>\n<p>La nostra lana della Nuova Zelanda proviene da allevamenti certificati secondo il Responsible Wool Standard (RWS): uno standard indipendente per il benessere animale e la gestione responsabile del territorio. Le pecore sono accudite secondo standard di benessere riconosciuti e il terreno \u00e8 gestito in modo sostenibile. Scegliere questo filato sostiene queste pratiche agricole.<br \/>\n&nbsp;<\/p>\n<h2>Domande frequenti<\/h2>\n<div class=\"accordion\">\r\n\t<div id=\"accordion-2199645332\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2199645332-label\" class=\"accordion-title plain active\" href=\"#accordion-item-posso-usare-questo-filato-di-lana-con-qualsiasi-macchina-tufting?\" aria-expanded=\"true\" aria-controls=\"accordion-2199645332-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Posso usare questo filato di lana con qualsiasi macchina tufting?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2199645332-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-2199645332-label\">\n\t\t\t\r\n<p>S\u00ec. \u00c8 filato per macchine tufting standard a pelo tagliato e pelo ad anello, incluse le nostre pistole AK-V e AK-1N Duo. A 837\/3 tex scorre senza intoppi attraverso un ago da 4 mm, a filo singolo o doppio, senza ostruzioni.  <\/p>\r\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div id=\"accordion-1554233427\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1554233427-label\" class=\"accordion-title plain\" href=\"#accordion-item-quanto-filato-mi-serve-per-un-tappeto-tufted?\" aria-expanded=\"false\" aria-controls=\"accordion-1554233427-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Quanto filato mi serve per un tappeto tufted?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1554233427-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1554233427-label\">\n\t\t\t\r\n<p>Una guida approssimativa, utilizzo tufted a filo doppio.<\/p>\r\n<ul>\r\n<li>30 x 30 cm: circa mezzo cono (circa 225 g)<\/li>\r\n<li>60 x 60 cm: da 1,5 a 2 coni (circa 700-900 g)<\/li>\r\n<li>90 x 90 cm: da 3 a 4 coni (circa 1,4-1,8 kg)<\/li>\r\n<li>120 x 120 cm: da 5 a 7 coni (circa 2,3-3,2 kg)<\/li>\r\n<\/ul>\r\n<p>Il pelo alto (da 20 a 60 mm) utilizza circa 2-3 volte di pi\u00f9 rispetto al pelo basso (da 7 a 18 mm). Il pelo ad anello utilizza leggermente meno del pelo tagliato. <\/p>\r\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div id=\"accordion-2548825154\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2548825154-label\" class=\"accordion-title plain\" href=\"#accordion-item-come-pulisco-il-mio-tappeto-tufted-in-lana?\" aria-expanded=\"false\" aria-controls=\"accordion-2548825154-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Come pulisco il mio tappeto tufted in lana?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2548825154-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2548825154-label\">\n\t\t\t\r\n<p>La lana gestisce bene l'umidit\u00e0. Per le macchie, pulisci localmente con acqua fredda e un po' di detergente delicato, poi lascia asciugare all'aria. Non lavare in lavatrice e non asciugare mai in asciugatrice, poich\u00e9 il calore restringe la lana.  <\/p>\r\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div id=\"accordion-3722681557\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3722681557-label\" class=\"accordion-title plain\" href=\"#accordion-item-perch\u00e9-scegliere-il-filato-100%-lana-per-tufting?\" aria-expanded=\"false\" aria-controls=\"accordion-3722681557-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Perch\u00e9 scegliere il filato 100% lana per tufting?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3722681557-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3722681557-label\">\n\t\t\t\r\n<p>La lana \u00e8 la fibra che dura. \u00c8 naturalmente resiliente, quindi il pelo si riprende invece di schiacciarsi, ed \u00e8 naturalmente ignifuga. Funziona sia con macchine a pelo tagliato che a pelo ad anello e mantiene la sua resistenza e il suo colore nel corso degli anni, motivo per cui \u00e8 lo standard per i pezzi che vendi, esponi o conservi.  <\/p>\r\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div id=\"accordion-746162636\" class=\"accordion-item\">\n\t\t<a id=\"accordion-746162636-label\" class=\"accordion-title plain\" href=\"#accordion-item-il-filato-\u00e8-resistente-allo-sbiadimento?\" aria-expanded=\"false\" aria-controls=\"accordion-746162636-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Il filato \u00e8 resistente allo sbiadimento?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-746162636-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-746162636-label\">\n\t\t\t\r\n<p>S\u00ec, mantiene bene il colore con l'uso normale. Per mantenerlo cos\u00ec, pulisci localmente con acqua fredda anzich\u00e9 calda ed evita lunghi periodi alla luce solare diretta, che sbiadisce qualsiasi fibra tinta nel tempo. <\/p>\r\n\t\t<\/div>\n\t<\/div>\n\t\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Viola Scuro \u00e8 un viola ricco e profondo in lana neozelandese 100%, filata specificamente per il tufting. 600 m per cono da 500 g, copertura eccellente, mantiene il colore per anni. <\/p>\n","protected":false},"featured_media":48589,"template":"","meta":{"bwfblock_default_font":""},"product_brand":[],"product_cat":[452,1311],"product_tag":[],"class_list":["post-48966","product","type-product","status-publish","has-post-thumbnail","product_cat-filato","product_cat-filato-di-lana-per-tufting","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/product\/48966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/media\/48589"}],"wp:attachment":[{"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/media?parent=48966"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/product_brand?post=48966"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/product_cat?post=48966"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tuftingeurope.com\/it\/wp-json\/wp\/v2\/product_tag?post=48966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}